{"id":682,"date":"2024-07-12T02:54:34","date_gmt":"2024-07-12T00:54:34","guid":{"rendered":"https:\/\/www.sebastianfranco.net\/shop\/"},"modified":"2024-07-12T02:54:34","modified_gmt":"2024-07-12T00:54:34","slug":"shop","status":"publish","type":"page","link":"https:\/\/www.sebastianfranco.net\/en\/shop\/","title":{"rendered":"Shop"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-682","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.sebastianfranco.net\/en\/wp-json\/wp\/v2\/pages\/682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sebastianfranco.net\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sebastianfranco.net\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sebastianfranco.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sebastianfranco.net\/en\/wp-json\/wp\/v2\/comments?post=682"}],"version-history":[{"count":0,"href":"https:\/\/www.sebastianfranco.net\/en\/wp-json\/wp\/v2\/pages\/682\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sebastianfranco.net\/en\/wp-json\/wp\/v2\/media?parent=682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}